{"id":22006,"date":"2026-04-29T21:13:24","date_gmt":"2026-04-29T19:13:24","guid":{"rendered":"https:\/\/ongamic.teamdesarrollo.com\/escola-innova\/"},"modified":"2026-05-05T10:46:22","modified_gmt":"2026-05-05T08:46:22","slug":"escuela-innova","status":"publish","type":"page","link":"https:\/\/ongamic.org\/es\/escuela-innova\/","title":{"rendered":"Construcci\u00f3n y equipamiento de la Escuela Innova"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"22006\" class=\"elementor elementor-22006 elementor-692\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-613b559b e-flex e-con-boxed e-con e-parent\" data-id=\"613b559b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72166d4a elementor-widget elementor-widget-heading\" data-id=\"72166d4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Construcci\u00f3n y equipamiento de la Escuela Innova<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b7203dc elementor-align-right elementor-widget elementor-widget-breadcrumbs\" data-id=\"4b7203dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t\t<nav id=\"breadcrumbs\"><span><span><a href=\"https:\/\/ongamic.org\/es\/\">Inicio<\/a><\/span><\/span><\/nav>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed1ca28 e-flex e-con-boxed e-con e-parent\" data-id=\"ed1ca28\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b93a694 e-con-full e-flex e-con e-child\" data-id=\"b93a694\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d9ff20e e-con-full e-flex e-con e-child\" data-id=\"d9ff20e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32cc126 elementor-widget elementor-widget-text-editor\" data-id=\"32cc126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Para muchos ni\u00f1os de Guinea Bissau, ir a la escuela es un lujo que no pueden permitirse. Las escuelas p\u00fablicas pr\u00e1cticamente no funcionan y la adquisici\u00f3n del material escolar supone un coste que, para muchas familias, es inalcanzable.\u00a0<\/p><p>En el curso 2019-2020 abrimos la Escuela Innova a la comunidad en un edificio que ya hab\u00edamos construido y que ahora pertenece a nuestra contraparte local Casa Emanuel. Se realizaron las obras necesarias para adaptarlo a su nuevo uso y se equip\u00f3. As\u00ed se consigui\u00f3 un centro con 4 aulas, una peque\u00f1a secretar\u00eda y un espacio donde elaborar la comida diaria de los alumnos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23679b9 e-con-full e-flex e-con e-child\" data-id=\"23679b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92f14e4 elementor-widget elementor-widget-image\" data-id=\"92f14e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"228\" src=\"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/Obrers-a-lEscola-Bissalanca-1.webp\" class=\"attachment-full size-full wp-image-22027 not-transparent\" alt=\"\" data-has-transparency=\"false\" data-dominant-color=\"978779\" style=\"--dominant-color: #978779\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5280d6 e-con-full e-flex e-con e-child\" data-id=\"a5280d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3afdaa5 e-con-full e-flex e-con e-child\" data-id=\"3afdaa5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c6e59e elementor-widget elementor-widget-image\" data-id=\"4c6e59e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"809\" src=\"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/escola-innova.webp\" class=\"attachment-full size-full wp-image-22028 not-transparent\" alt=\"\" srcset=\"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/escola-innova.webp 1080w, https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/escola-innova-600x449.webp 600w, https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/escola-innova-300x225.webp 300w, https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/escola-innova-1024x767.webp 1024w, https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/escola-innova-768x575.webp 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" data-has-transparency=\"false\" data-dominant-color=\"7c6058\" style=\"--dominant-color: #7c6058\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9f66f3d e-con-full e-flex e-con e-child\" data-id=\"9f66f3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d35cd6f elementor-widget elementor-widget-text-editor\" data-id=\"d35cd6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Pero la demanda de escolarizaci\u00f3n en el segundo curso super\u00f3 todas las previsiones y el centro se qued\u00f3 peque\u00f1o. Por ello, comenzamos la construcci\u00f3n de un nuevo centro que, adem\u00e1s de ofrecer educaci\u00f3n primaria a los ni\u00f1os m\u00e1s vulnerables de la zona, tambi\u00e9n pudiera ofrecer cursos de alfabetizaci\u00f3n a mujeres y j\u00f3venes analfabetos. Esta fue la demanda de la poblaci\u00f3n.\u00a0<\/p><p>Para continuar adelante con este proyecto necesitamos tu ayuda para finalizar la obra y equipar el centro con el fin de convertirlo en una escuela. \u00bfC\u00f3mo se invertir\u00eda tu apoyo econ\u00f3mico?<\/p><ul><li>Finalizar la construcci\u00f3n del centro<\/li><li>Equipar todas las aulas con mesas, sillas y pizarras<\/li><li>Equipar todas las aulas con ventiladores<\/li><li>Equipar la cocina con fogones, nevera, utensilios de cocina y material<\/li><li>Dotar al centro de electricidad<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60d8575 e-con-full e-flex e-con e-child\" data-id=\"60d8575\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bd2ad59 e-con-full e-flex e-con e-child\" data-id=\"bd2ad59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54de63e elementor-widget elementor-widget-heading\" data-id=\"54de63e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo ser\u00e1 la nueva Escuela Innova?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f71760 elementor-widget elementor-widget-text-editor\" data-id=\"9f71760\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Situado en un terreno de unos 2.700 metros cuadrados, el nuevo edificio de la Escuela Innova tendr\u00e1 dos plantas que albergar\u00e1n 8 aulas, una cocina-laboratorio, una sala polivalente (que servir\u00e1 como biblioteca, sala de reuniones con padres y madres, zona de alfabetizaci\u00f3n de mujeres y j\u00f3venes analfabetos), ba\u00f1os para alumnos y profesores, secretar\u00eda y direcci\u00f3n. Tambi\u00e9n contar\u00e1 con una zona de almac\u00e9n, un amplio patio y un espacio destinado al huerto escolar.&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b90828 e-con-full e-flex e-con e-child\" data-id=\"0b90828\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0dfb36c elementor-widget elementor-widget-image\" data-id=\"0dfb36c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"228\" src=\"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/Construccio-escola-Bissalanca-1.webp\" class=\"attachment-full size-full wp-image-22029 not-transparent\" alt=\"\" data-has-transparency=\"false\" data-dominant-color=\"978e87\" style=\"--dominant-color: #978e87\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-760d210 e-flex e-con-boxed e-con e-parent\" data-id=\"760d210\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e09976 elementor-widget elementor-widget-shortcode\" data-id=\"7e09976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f22163-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"22163\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/22006#wpcf7-f22163-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"22163\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f22163-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-amic-donacio\">\n\t<div class=\"amic-seccio\">\n\t\t<p><label class=\"amic-label\">Importe (\u20ac)<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"import\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number amic-input-field\" min=\"1\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"10,00\" value=\"\" type=\"number\" name=\"import\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"projecte-id\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text amic-camp-ocult\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"projecte-id\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"amic-seccio\">\n\t\t<p><label class=\"amic-label\">Informaci\u00f3n personal<\/label>\n\t\t<\/p>\n\t\t<div class=\"amic-row\">\n\t\t\t<div class=\"amic-col\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"nom\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required amic-input-field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre *\" value=\"\" type=\"text\" name=\"nom\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"amic-col\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"cognoms\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required amic-input-field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apellidos *\" value=\"\" type=\"text\" name=\"cognoms\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email amic-input-field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico *\" value=\"\" type=\"email\" name=\"email\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nif\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text amic-input-field\" aria-invalid=\"false\" placeholder=\"DNI \/ NIF (para el certificado fiscal)\" value=\"\" type=\"text\" name=\"nif\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"amic-seccio\">\n\t\t<p><label class=\"amic-label\">Datos de facturaci\u00f3n<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"pais\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required amic-input-field\" aria-required=\"true\" aria-invalid=\"false\" name=\"pais\"><option value=\"Espa\u00f1a\" selected=\"selected\">Espa\u00f1a<\/option><option value=\"Andorra\">Andorra<\/option><option value=\"Francia\">Francia<\/option><option value=\"Portugal\">Portugal<\/option><option value=\"Italia\">Italia<\/option><option value=\"Alemania\">Alemania<\/option><option value=\"Reino Unido\">Reino Unido<\/option><option value=\"Estados Unidos\">Estados Unidos<\/option><option value=\"M\u00e9xico\">M\u00e9xico<\/option><option value=\"Argentina\">Argentina<\/option><option value=\"Colombia\">Colombia<\/option><option value=\"Senegal\">Senegal<\/option><option value=\"Gambia\">Gambia<\/option><option value=\"Otros\">Otros<\/option><\/select><\/span>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"direccio-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required amic-input-field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Direcci\u00f3n l\u00ednea 1 *\" value=\"\" type=\"text\" name=\"direccio-1\" \/><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"direccio-2\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text amic-input-field\" aria-invalid=\"false\" placeholder=\"Direcci\u00f3n l\u00ednea 2\" value=\"\" type=\"text\" name=\"direccio-2\" \/><\/span>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ciutat\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required amic-input-field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Ciudad *\" value=\"\" type=\"text\" name=\"ciutat\" \/><\/span>\n\t\t<\/p>\n\t\t<div class=\"amic-row\">\n\t\t\t<div class=\"amic-col\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"provincia\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required amic-input-field\" aria-required=\"true\" aria-invalid=\"false\" name=\"provincia\"><option value=\"Barcelona\" selected=\"selected\">Barcelona<\/option><option value=\"Girona\">Girona<\/option><option value=\"Lleida\">Lleida<\/option><option value=\"Tarragona\">Tarragona<\/option><option value=\"Otras\">Otras<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t<div class=\"amic-col\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"codi-postal\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required amic-input-field\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"C\u00f3digo postal *\" value=\"\" type=\"text\" name=\"codi-postal\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"amic-seccio\">\n\t\t<p><label class=\"amic-label\">Comentario<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"comentari\"><textarea cols=\"40\" rows=\"3\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea amic-input-field\" aria-invalid=\"false\" placeholder=\"Deja un comentario\" name=\"comentari\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"amic-seccio\">\n\t\t<p><label class=\"amic-label\">Seleccionar la forma de pago<\/label>\n\t\t<\/p>\n\t\t<div class=\"amic-selector-pagament\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"forma-pagament\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><label><input type=\"radio\" name=\"forma-pagament\" value=\"Bizum Solidario\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">Bizum Solidario<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"radio\" name=\"forma-pagament\" value=\"Transferencia Bancaria\" \/><span class=\"wpcf7-list-item-label\">Transferencia Bancaria<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"amic-caixa-info\">\n\t\t<p class=\"amic-titol-caixa\">Datos para realizar el pago:\n\t\t<\/p>\n\t\t<div class=\"amic-metode-detall\">\n\t\t\t<p><strong>BIZUM SOLIDARIO:<\/strong>\n\t\t\t<\/p>\n\t\t\t<p>C\u00f3digo: <span class=\"amic-highlight\">13192<\/span>\n\t\t\t<\/p>\n\t\t\t<p><small>(Dentro de tu App del banco, busca la opci\u00f3n \"Donar\" o \"Bizum Solidario\" e introduce el c\u00f3digo).<\/small>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"amic-metode-detall\" style=\"margin-top:15px;\">\n\t\t\t<p><strong>TRANSFERENCIA:<\/strong>\n\t\t\t<\/p>\n\t\t\t<p>IBAN: <span class=\"amic-highlight\">ES31 0081 1774 1500 0103 6608<\/span>\n\t\t\t<\/p>\n\t\t\t<p><small>Banco: Sabadell | SWIFT: BSABESBB | Titular: ONG AMIC<\/small>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<p class=\"amic-recordatori\">Por favor, indica tu <strong>Nombre y DNI<\/strong> en el concepto para que podamos identificar tu donaci\u00f3n.\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"amic-seccio\">\n\t\t<div class=\"amic-acceptacio\" style=\"padding: 10px; margin-bottom: 15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"politica\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"politica\" value=\"1\" id=\"politica\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y estoy conforme con la <a style=\"text-decoration: underline;\" href=\"\/es\/politica-de-privacidad\/\" target=\"_blank\">pol\u00edtica de privacidad<\/a> y el <a style=\"text-decoration: underline;\" href=\"\/es\/aviso-legal\/\" target=\"_blank\">aviso legal<\/a>.<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner amic-btn-submit\" type=\"submit\" value=\"Dona Ahora\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce0f59 elementor-widget elementor-widget-html\" data-id=\"3ce0f59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script>\nwindow.addEventListener('load', function() {\n    \/\/ Esperem un moment perqu\u00e8 el formulari estigui ben carregat\n    setTimeout(function() {\n        \/\/ Busquem el t\u00edtol de l'H1 de la p\u00e0gina (que sol ser el nom del projecte)\n        \/\/ Si prefereixes el t\u00edtol de la pestanya, usa document.title\n        var titolProjecte = document.querySelector('h1').innerText || document.title;\n        \n        \/\/ Busquem el camp del formulari\n        var camps = document.getElementsByName(\"projecte-id\");\n        \n        if(camps.length > 0) {\n            camps[0].value = titolProjecte;\n        }\n    }, 500);\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Construcci\u00f3n y equipamiento de la Escuela Innova Para muchos ni\u00f1os de Guinea Bissau, ir a la escuela es un lujo que no pueden permitirse. Las escuelas p\u00fablicas pr\u00e1cticamente no funcionan y la adquisici\u00f3n del material escolar supone un coste que, para muchas familias, es inalcanzable.\u00a0 En el curso 2019-2020 abrimos la Escuela Innova a la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":["post-22006","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Construcci\u00f3n y equipamiento de la Escuela Innova - ONG Amic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ongamic.org\/es\/escuela-innova\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Construcci\u00f3n y equipamiento de la Escuela Innova - ONG Amic\" \/>\n<meta property=\"og:description\" content=\"Construcci\u00f3n y equipamiento de la Escuela Innova Para muchos ni\u00f1os de Guinea Bissau, ir a la escuela es un lujo que no pueden permitirse. Las escuelas p\u00fablicas pr\u00e1cticamente no funcionan y la adquisici\u00f3n del material escolar supone un coste que, para muchas familias, es inalcanzable.\u00a0 En el curso 2019-2020 abrimos la Escuela Innova a la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ongamic.org\/es\/escuela-innova\/\" \/>\n<meta property=\"og:site_name\" content=\"ONG Amic\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T08:46:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/Obrers-a-lEscola-Bissalanca-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"228\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/escuela-innova\\\/\",\"url\":\"https:\\\/\\\/ongamic.org\\\/es\\\/escuela-innova\\\/\",\"name\":\"Construcci\u00f3n y equipamiento de la Escuela Innova - ONG Amic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/escuela-innova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/escuela-innova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Obrers-a-lEscola-Bissalanca-1.webp\",\"datePublished\":\"2026-04-29T19:13:24+00:00\",\"dateModified\":\"2026-05-05T08:46:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/escuela-innova\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ongamic.org\\\/es\\\/escuela-innova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/escuela-innova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Obrers-a-lEscola-Bissalanca-1.webp\",\"contentUrl\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Obrers-a-lEscola-Bissalanca-1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/escuela-innova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ongamic.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Construcci\u00f3n y equipamiento de la Escuela Innova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ongamic.org\\\/es\\\/\",\"name\":\"ONG Amic\",\"description\":\"ONG que treballa a Guinea Bissau\",\"publisher\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ongamic.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/#organization\",\"name\":\"ONG Amic\",\"url\":\"https:\\\/\\\/ongamic.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-ONGamic.webp\",\"contentUrl\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-ONGamic.webp\",\"width\":230,\"height\":70,\"caption\":\"ONG Amic\"},\"image\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Construcci\u00f3n y equipamiento de la Escuela Innova - ONG Amic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ongamic.org\/es\/escuela-innova\/","og_locale":"es_ES","og_type":"article","og_title":"Construcci\u00f3n y equipamiento de la Escuela Innova - ONG Amic","og_description":"Construcci\u00f3n y equipamiento de la Escuela Innova Para muchos ni\u00f1os de Guinea Bissau, ir a la escuela es un lujo que no pueden permitirse. Las escuelas p\u00fablicas pr\u00e1cticamente no funcionan y la adquisici\u00f3n del material escolar supone un coste que, para muchas familias, es inalcanzable.\u00a0 En el curso 2019-2020 abrimos la Escuela Innova a la [&hellip;]","og_url":"https:\/\/ongamic.org\/es\/escuela-innova\/","og_site_name":"ONG Amic","article_modified_time":"2026-05-05T08:46:22+00:00","og_image":[{"width":300,"height":228,"url":"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/Obrers-a-lEscola-Bissalanca-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ongamic.org\/es\/escuela-innova\/","url":"https:\/\/ongamic.org\/es\/escuela-innova\/","name":"Construcci\u00f3n y equipamiento de la Escuela Innova - ONG Amic","isPartOf":{"@id":"https:\/\/ongamic.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ongamic.org\/es\/escuela-innova\/#primaryimage"},"image":{"@id":"https:\/\/ongamic.org\/es\/escuela-innova\/#primaryimage"},"thumbnailUrl":"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/Obrers-a-lEscola-Bissalanca-1.webp","datePublished":"2026-04-29T19:13:24+00:00","dateModified":"2026-05-05T08:46:22+00:00","breadcrumb":{"@id":"https:\/\/ongamic.org\/es\/escuela-innova\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ongamic.org\/es\/escuela-innova\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ongamic.org\/es\/escuela-innova\/#primaryimage","url":"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/Obrers-a-lEscola-Bissalanca-1.webp","contentUrl":"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/05\/Obrers-a-lEscola-Bissalanca-1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/ongamic.org\/es\/escuela-innova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ongamic.org\/es\/"},{"@type":"ListItem","position":2,"name":"Construcci\u00f3n y equipamiento de la Escuela Innova"}]},{"@type":"WebSite","@id":"https:\/\/ongamic.org\/es\/#website","url":"https:\/\/ongamic.org\/es\/","name":"ONG Amic","description":"ONG que treballa a Guinea Bissau","publisher":{"@id":"https:\/\/ongamic.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ongamic.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ongamic.org\/es\/#organization","name":"ONG Amic","url":"https:\/\/ongamic.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ongamic.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/04\/logo-ONGamic.webp","contentUrl":"https:\/\/ongamic.org\/wp-content\/uploads\/2026\/04\/logo-ONGamic.webp","width":230,"height":70,"caption":"ONG Amic"},"image":{"@id":"https:\/\/ongamic.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/pages\/22006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/comments?post=22006"}],"version-history":[{"count":4,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/pages\/22006\/revisions"}],"predecessor-version":[{"id":22034,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/pages\/22006\/revisions\/22034"}],"wp:attachment":[{"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/media?parent=22006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}