{"id":20822,"date":"2024-04-12T10:22:36","date_gmt":"2024-04-12T10:22:36","guid":{"rendered":"https:\/\/ongamic.org\/?p=20822"},"modified":"2024-04-12T10:23:42","modified_gmt":"2024-04-12T10:23:42","slug":"ampliacion-escola-innova","status":"publish","type":"post","link":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/","title":{"rendered":"Ampliaci\u00f3n de la Escola Innova"},"content":{"rendered":"<p>El nuevo edificio de la Escola Innova ya es una realidad. Ahora trabajamos para poder abrir las puertas del nuevo curso 2024-25, el mes de septiembre. El objetivo contin\u00faa siendo el mismo que nos llev\u00f3 a abrir las puertas el 2019 de la primera Escola Internacional Innova, ofrecer a los ni\u00f1os m\u00e1s vulnerables de la comunidad de Bissalanca (Guinea-Bissau) una educaci\u00f3n de calidad accesible.<\/p>\n<p><!--more--><\/p>\n<h2>La Escola Innova<\/h2>\n<p><span style=\"font-weight: 400;\">La Escola Innova abri\u00f3 las puertas en 2019, acogiendo a 46 ni\u00f1os de entre 6-8 a\u00f1os de las familias m\u00e1s desfavorecidas de la comunidad. Hoy en d\u00eda, un total de 173 alumnos est\u00e1n escolarizados en cursos que van desde primero hasta sexto de primaria.<\/span><\/p>\n<h2>Reformas y resultados<\/h2>\n<p><span style=\"font-weight: 400;\">A causa de la gran demanda de nuevos estudiantes, el diciembre de 2020 compramos un terreno de 2.400 metros cuadrados, el cual est\u00e1 situado a 700 metros de la antigua escuela. Las obras empezaron el enero de 2021, primeramente con la valla perimetral y sus puertas y siguiendo por la fuente de agua y el contenedor (el cual hoy en d\u00eda se utiliza de almac\u00e9n).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Posteriormente, empez\u00f3 la construcci\u00f3n de la Nova Escola Innova, la cual tiene 432 metros cuadrados distribuidos en dos plantas. Desde las primeras etapas de planificaci\u00f3n hasta la culminaci\u00f3n de la construcci\u00f3n, cada detalle de la Nova Escola Innova ha sido cuidadosamente considerado para garantizar un entorno inclusivo para todos.<\/span><\/p>\n<h3><b>Planta baja<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">En la planta baja, podemos encontrar dos aulas, cada una de ellas medida aproximadamente 50 metros cuadrados y tiene capacidad para unos 25 alumnos. Por otro lado, tambi\u00e9n tiene una cocina\/laboratorio en la cual se har\u00e1 tanto la comida de los ni\u00f1os como experimentos cient\u00edficos aplicados a los conceptos que est\u00e1n estudiando en clase. Estamos especialmente orgullosos de tener un laboratorio, ya que son pocos los centros en esta comunidad que tienen uno e incluso, a veces, las escuelas de m\u00e1s alto prestigio carecen de esto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Continuando con la planta baja, encontramos un comedor que, aunque actualmente tiene las mesas a cuerpo descubierto, estamos en proceso de construcci\u00f3n para techar la zona y que as\u00ed los ni\u00f1os est\u00e9n tapados. En el patio, encontraremos la pista deportiva, donde los m\u00e1s peque\u00f1os, a trav\u00e9s de juegos, aprender\u00e1n valores tan importantes como el esfuerzo, el respeto y el trabajo en equipo, y el djemberem (lugar de reuni\u00f3n de los alumnos). En el patio tambi\u00e9n tenemos un pozo el cual suministra agua a toda la escuela.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para acabar con esta planta, encontramos la zona del ba\u00f1o. Esta tiene 5 lavabos, 1 de ellos (el de profesores) tiene un plato de ducha. Mucha gente no tiene agua corriente en casa y necesita andar muchos kil\u00f3metros hasta llegar a la escuela, es por eso que, todo aqu\u00e9l que lo desee, sea alumno o profesor, podr\u00e1 ducharse en estos ba\u00f1os.<\/span><\/p>\n<h3>Primera planta<\/h3>\n<p><span style=\"font-weight: 400;\">Subiendo por las escaleras, accedemos a la primera planta. Podremos ver que las escaleras se encuentran techadas para evitar que los alumnos y profesores se mojen durante la \u00e9poca de lluvia y, bajo estas, se encuentra el almac\u00e9n. Por otro lado, el suelo de toda la escuela es antideslizante para evitar posibles accidentes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las vistas desde la segunda planta son impresionantes: podemos ver parte de Bissau, Bissalanca y su aeropuerto. La valla de esta primera planta es muy alta para evitar accidentes con los m\u00e1s peque\u00f1os. Continuando con el recorrido natural,\u00a0 encontramos la secretar\u00eda y direcci\u00f3n de la escuela, desde donde se coordinar\u00e1 todo el centro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Prosiguiendo, encontramos las 2 aulas restantes, igual de grandes que las de la planta inferior y abiertas por todos los lados posibles para ofrecer una buena ventilaci\u00f3n y, acabando el recorrido, la sala polivalente. Esta sala, de 70 metros cuadrados, est\u00e1 pensada para realizar actividades grupales con el alumnado y la alfabetizaci\u00f3n de mujeres por las tardes (tarea que se est\u00e1 realizando actualmente en la otra escuela), aunque tambi\u00e9n se convertir\u00e1 en biblioteca.<\/span><\/p>\n<p><iframe title=\"Nueva Escola Innova en Bissalanca\" width=\"1060\" height=\"596\" src=\"https:\/\/www.youtube.com\/embed\/WzpHlpVL4yk?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/ongamic.org\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h2>El futuro<\/h2>\n<p><span style=\"font-weight: 400;\">Todav\u00eda carecemos de mobiliario y faltan peque\u00f1as reformas mencionadas anteriormente, pero nuestro compromiso no se para en la ampliaci\u00f3n de la escuela. Tambi\u00e9n nos dedicamos a capacitar a nuestros maestros, asegurando que tengan las habilidades y el conocimiento necesario para conducir a nuestros estudiantes hacia un futuro brillante y lleno de posibilidades.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nuestra idea es abrir las puertas de esta nueva escuela en septiembre para poder distribuir a los alumnos: mientras que en la Escola Innova ir\u00edan los ni\u00f1os de p5 a quinto, en la Nova Escola Innova ir\u00edan los ni\u00f1os de sexto a noveno curso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este proyecto representa un sue\u00f1o hecho realidad gracias a la Asociaci\u00f3n Casa Emanuel, la Fundaci\u00f3n Dr. Ivan Ma\u00f1ero y el apoyo invaluable de nuestros padrinos y madrinas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo edificio de la Escola Innova ya es una realidad. Ahora trabajamos para poder abrir las puertas del nuevo curso 2024-25, el mes de septiembre. El objetivo contin\u00faa siendo el mismo que nos llev\u00f3 a abrir las puertas el 2019 de la primera Escola Internacional Innova, ofrecer a los ni\u00f1os m\u00e1s vulnerables de la&#8230;<\/p>\n","protected":false},"author":144,"featured_media":20823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[13],"tags":[],"class_list":["post-20822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ampliaci\u00f3n de la Escola Innova - Amic ONG<\/title>\n<meta name=\"description\" content=\"El nuevo edificio de la Escola Innova ya es una realidad. Ahora trabajamos para poder abrir las puertas del nuevo curso 2024-25, el mes de septiembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ampliaci\u00f3n de la Escola Innova - Amic ONG\" \/>\n<meta property=\"og:description\" content=\"El nuevo edificio de la Escola Innova ya es una realidad. Ahora trabajamos para poder abrir las puertas del nuevo curso 2024-25, el mes de septiembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/\" \/>\n<meta property=\"og:site_name\" content=\"Amic ONG\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-12T10:22:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T10:23:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ongamic.org\/wp-content\/uploads\/2024\/04\/portada1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Judith\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Judith\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/\"},\"author\":{\"name\":\"Judith\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/#\\\/schema\\\/person\\\/0616f188109d8516f4b1249cda83c779\"},\"headline\":\"Ampliaci\u00f3n de la Escola Innova\",\"datePublished\":\"2024-04-12T10:22:36+00:00\",\"dateModified\":\"2024-04-12T10:23:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/\"},\"wordCount\":821,\"publisher\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/portada1-scaled.jpg\",\"articleSection\":[\"General @es\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/\",\"url\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/\",\"name\":\"Ampliaci\u00f3n de la Escola Innova - Amic ONG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/portada1-scaled.jpg\",\"datePublished\":\"2024-04-12T10:22:36+00:00\",\"dateModified\":\"2024-04-12T10:23:42+00:00\",\"description\":\"El nuevo edificio de la Escola Innova ya es una realidad. Ahora trabajamos para poder abrir las puertas del nuevo curso 2024-25, el mes de septiembre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/portada1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/portada1-scaled.jpg\",\"width\":2560,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/es\\\/ampliacion-escola-innova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/ongamic.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ampliaci\u00f3n de la Escola Innova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/#website\",\"url\":\"https:\\\/\\\/ongamic.org\\\/\",\"name\":\"ONG AMIC\",\"description\":\"ONG que treballa a Guinea Bissau\",\"publisher\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ongamic.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/#organization\",\"name\":\"ONG AMIC\",\"url\":\"https:\\\/\\\/ongamic.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-amic-per-adhesiu.png\",\"contentUrl\":\"https:\\\/\\\/ongamic.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-amic-per-adhesiu.png\",\"width\":1033,\"height\":591,\"caption\":\"ONG AMIC\"},\"image\":{\"@id\":\"https:\\\/\\\/ongamic.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ong_amic\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ongamic.org\\\/#\\\/schema\\\/person\\\/0616f188109d8516f4b1249cda83c779\",\"name\":\"Judith\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb3684726f4cf3c2d07908753f7eb6eb78788cb146b8bdd38b7be22a89c9e2d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb3684726f4cf3c2d07908753f7eb6eb78788cb146b8bdd38b7be22a89c9e2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bb3684726f4cf3c2d07908753f7eb6eb78788cb146b8bdd38b7be22a89c9e2d?s=96&d=mm&r=g\",\"caption\":\"Judith\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ampliaci\u00f3n de la Escola Innova - Amic ONG","description":"El nuevo edificio de la Escola Innova ya es una realidad. Ahora trabajamos para poder abrir las puertas del nuevo curso 2024-25, el mes de septiembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/","og_locale":"es_ES","og_type":"article","og_title":"Ampliaci\u00f3n de la Escola Innova - Amic ONG","og_description":"El nuevo edificio de la Escola Innova ya es una realidad. Ahora trabajamos para poder abrir las puertas del nuevo curso 2024-25, el mes de septiembre.","og_url":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/","og_site_name":"Amic ONG","article_published_time":"2024-04-12T10:22:36+00:00","article_modified_time":"2024-04-12T10:23:42+00:00","og_image":[{"width":2560,"height":1152,"url":"https:\/\/ongamic.org\/wp-content\/uploads\/2024\/04\/portada1-scaled.jpg","type":"image\/jpeg"}],"author":"Judith","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Judith","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/#article","isPartOf":{"@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/"},"author":{"name":"Judith","@id":"https:\/\/ongamic.org\/#\/schema\/person\/0616f188109d8516f4b1249cda83c779"},"headline":"Ampliaci\u00f3n de la Escola Innova","datePublished":"2024-04-12T10:22:36+00:00","dateModified":"2024-04-12T10:23:42+00:00","mainEntityOfPage":{"@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/"},"wordCount":821,"publisher":{"@id":"https:\/\/ongamic.org\/#organization"},"image":{"@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/#primaryimage"},"thumbnailUrl":"https:\/\/ongamic.org\/wp-content\/uploads\/2024\/04\/portada1-scaled.jpg","articleSection":["General @es"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/","url":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/","name":"Ampliaci\u00f3n de la Escola Innova - Amic ONG","isPartOf":{"@id":"https:\/\/ongamic.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/#primaryimage"},"image":{"@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/#primaryimage"},"thumbnailUrl":"https:\/\/ongamic.org\/wp-content\/uploads\/2024\/04\/portada1-scaled.jpg","datePublished":"2024-04-12T10:22:36+00:00","dateModified":"2024-04-12T10:23:42+00:00","description":"El nuevo edificio de la Escola Innova ya es una realidad. Ahora trabajamos para poder abrir las puertas del nuevo curso 2024-25, el mes de septiembre.","breadcrumb":{"@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/#primaryimage","url":"https:\/\/ongamic.org\/wp-content\/uploads\/2024\/04\/portada1-scaled.jpg","contentUrl":"https:\/\/ongamic.org\/wp-content\/uploads\/2024\/04\/portada1-scaled.jpg","width":2560,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/ongamic.org\/es\/ampliacion-escola-innova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/ongamic.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ampliaci\u00f3n de la Escola Innova"}]},{"@type":"WebSite","@id":"https:\/\/ongamic.org\/#website","url":"https:\/\/ongamic.org\/","name":"ONG AMIC","description":"ONG que treballa a Guinea Bissau","publisher":{"@id":"https:\/\/ongamic.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ongamic.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ongamic.org\/#organization","name":"ONG AMIC","url":"https:\/\/ongamic.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ongamic.org\/#\/schema\/logo\/image\/","url":"https:\/\/ongamic.org\/wp-content\/uploads\/2023\/01\/logo-amic-per-adhesiu.png","contentUrl":"https:\/\/ongamic.org\/wp-content\/uploads\/2023\/01\/logo-amic-per-adhesiu.png","width":1033,"height":591,"caption":"ONG AMIC"},"image":{"@id":"https:\/\/ongamic.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ong_amic\/"]},{"@type":"Person","@id":"https:\/\/ongamic.org\/#\/schema\/person\/0616f188109d8516f4b1249cda83c779","name":"Judith","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6bb3684726f4cf3c2d07908753f7eb6eb78788cb146b8bdd38b7be22a89c9e2d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bb3684726f4cf3c2d07908753f7eb6eb78788cb146b8bdd38b7be22a89c9e2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bb3684726f4cf3c2d07908753f7eb6eb78788cb146b8bdd38b7be22a89c9e2d?s=96&d=mm&r=g","caption":"Judith"}}]}},"_links":{"self":[{"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/posts\/20822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/users\/144"}],"replies":[{"embeddable":true,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/comments?post=20822"}],"version-history":[{"count":0,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/posts\/20822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/media\/20823"}],"wp:attachment":[{"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/media?parent=20822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/categories?post=20822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ongamic.org\/es\/wp-json\/wp\/v2\/tags?post=20822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}